{"id":8922,"date":"2021-10-12T17:19:33","date_gmt":"2021-10-12T15:19:33","guid":{"rendered":"https:\/\/wmp.mx\/?p=8922"},"modified":"2021-10-12T17:20:11","modified_gmt":"2021-10-12T15:20:11","slug":"mexico-se-convierte-en-miembro-del-world-logistics-passport","status":"publish","type":"post","link":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/","title":{"rendered":"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos"},"content":{"rendered":"<p>El 4 de octubre de este a\u00f1o, la Secretar\u00eda de Econom\u00eda firm\u00f3 un nuevo acuerdo que convierte a M\u00e9xico en el miembro m\u00e1s reciente del \u201cWorld Logistics Passport\u201d. Con este, el pa\u00eds espera no s\u00f3lo llegar a nuevos mercados en el Medio Oriente, \u00c1frica y Asia, sino tambi\u00e9n reducir las barreras comerciales e impulsar el desarrollo econ\u00f3mico.<\/p>\n<h2><strong>\u00bfQu\u00e9 es el \u201cWorld Logistics Passport\u201d?<\/strong><\/h2>\n<p>Es una iniciativa de los Emiratos \u00c1rabes Unidos, que fue formada en 2020 durante el Foro Econ\u00f3mico Mundial en Davos. Adem\u00e1s de M\u00e9xico y los EAU, los miembros y\/o pa\u00edses con hubs principales son: Brasil, Colombia, Sud\u00e1frica, India, Indonesia, Tailandia, Etiop\u00eda, Botsuana, Zimbabue, Mozambique, Burkina Faso, Guinea, Malasia, Kenia, Paraguay, Ecuador, Kazajist\u00e1n, Uruguay, Marruecos, Senegal, Nigeria, Singapur y Vietnam. El objetivo del acuerdo es promover el comercio sur-sur y unir los puertos del Medio Oriente, \u00c1frica, Am\u00e9rica Latina y Asia. Con eso, los miembros esperan abrir nuevas rutas comerciales, acceder a nuevos mercados y tambi\u00e9n acelerar los flujos comerciales mundiales y hacer el comercio m\u00e1s eficiente.<\/p>\n<h2><strong>\u00bfQu\u00e9 papel desempe\u00f1a el Dub\u00e1i Port World?<\/strong><\/h2>\n<p>El mayor puerto del \u201cWorld Logistics Passport\u201d es el de Dub\u00e1i, que es un importante centro de comercio entre los pa\u00edses del sur. En 2019, el rendimiento del puerto fue de casi 70 millones de TEU (Unidad Equivalente a Veinte Pies), de los cuales casi 85% vienen de econom\u00edas emergentes. Por eso, el puerto es un centro clave en el comercio mundial, ya que el 40% de todo el comercio es de puerto a puerto.<\/p>\n<h2><strong>\u00bfCu\u00e1les son los beneficios para M\u00e9xico?<\/strong><\/h2>\n<p>La mayor oportunidad es probablemente la diversificaci\u00f3n de mercados, porque, aunque M\u00e9xico tiene un alto volumen de exportaci\u00f3n, la mayor parte se destina al mercado estadounidense y a Canad\u00e1. El nuevo acuerdo dar\u00e1 acceso a muchos nuevos mercados, especialmente en el Medio Oriente, \u00c1frica y Asia, lo que impulsar\u00e1 significativamente el desarrollo econ\u00f3mico del pa\u00eds. El \u201cWorld Logistics Passport\u201d tambi\u00e9n reducir\u00e1 las barreras comerciales. Esto facilitar\u00e1 el acceso a nuevos mercados, especialmente para las peque\u00f1as y medianas empresas (PYME), y permitir\u00e1 que m\u00e1s empresas participen en el comercio mundial. M\u00e9xico tambi\u00e9n espera reducir los costos comerciales y aumentar las importaciones y exportaciones. Sin embargo, el pa\u00eds tambi\u00e9n deber\u00eda tener cuidado con el \u201cWorld Logistics Passport\u201d y sus numerosas oportunidades nuevas, porqu\u00e9 ya tiene acuerdos comerciales con m\u00e1s de 40 pa\u00edses y no debe descuidar las relaciones existentes.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros. <a href=\"https:\/\/wmp.mx\/es\/servicios\/\"><strong>Aqu\u00ed<\/strong><\/a> encontrar\u00e1 un resumen de nuestros servicios.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>El 4 de octubre de este a\u00f1o, la Secretar\u00eda de Econom\u00eda firm\u00f3 un nuevo acuerdo que convierte a M\u00e9xico en el miembro m\u00e1s reciente del \u201cWorld Logistics Passport\u201d. Con este, el pa\u00eds espera no s\u00f3lo llegar a nuevos mercados en el Medio Oriente, \u00c1frica y Asia, sino tambi\u00e9n reducir las barreras comerciales e impulsar el [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":8926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-8922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos - WMP Mexico Advisors<\/title>\n<meta name=\"description\" content=\"\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos - WMP Mexico Advisors\" \/>\n<meta property=\"og:description\" content=\"\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/\" \/>\n<meta property=\"og:site_name\" content=\"WMP Mexico Advisors\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T15:19:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-12T15:20:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/KW40-Image-e1633564933371.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Liv Winterfeldt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liv Winterfeldt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/\"},\"author\":{\"name\":\"Liv Winterfeldt\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\"},\"headline\":\"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos\",\"datePublished\":\"2021-10-12T15:19:33+00:00\",\"dateModified\":\"2021-10-12T15:20:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/\"},\"wordCount\":474,\"image\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/KW40-Image-e1633564933371.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/\",\"url\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/\",\"name\":\"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos - WMP Mexico Advisors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/KW40-Image-e1633564933371.jpg\",\"datePublished\":\"2021-10-12T15:19:33+00:00\",\"dateModified\":\"2021-10-12T15:20:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\"},\"description\":\"\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/KW40-Image-e1633564933371.jpg\",\"contentUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/KW40-Image-e1633564933371.jpg\",\"width\":850,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/mexico-se-convierte-en-miembro-del-world-logistics-passport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wmp.mx\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#website\",\"url\":\"https:\\\/\\\/wmp.mx\\\/\",\"name\":\"WMP Mexico Advisors\",\"description\":\"Queretaro | Mexiko Stadt | Puebla | Stuttgart | Greenville\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wmp.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\",\"name\":\"Liv Winterfeldt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"caption\":\"Liv Winterfeldt\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos - WMP Mexico Advisors","description":"\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos - WMP Mexico Advisors","og_description":"\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.","og_url":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/","og_site_name":"WMP Mexico Advisors","article_published_time":"2021-10-12T15:19:33+00:00","article_modified_time":"2021-10-12T15:20:11+00:00","og_image":[{"width":850,"height":520,"url":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/KW40-Image-e1633564933371.jpg","type":"image\/jpeg"}],"author":"Liv Winterfeldt","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Liv Winterfeldt","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/#article","isPartOf":{"@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/"},"author":{"name":"Liv Winterfeldt","@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7"},"headline":"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos","datePublished":"2021-10-12T15:19:33+00:00","dateModified":"2021-10-12T15:20:11+00:00","mainEntityOfPage":{"@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/"},"wordCount":474,"image":{"@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/#primaryimage"},"thumbnailUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/KW40-Image-e1633564933371.jpg","articleSection":["News"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/","url":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/","name":"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos - WMP Mexico Advisors","isPartOf":{"@id":"https:\/\/wmp.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/#primaryimage"},"image":{"@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/#primaryimage"},"thumbnailUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/KW40-Image-e1633564933371.jpg","datePublished":"2021-10-12T15:19:33+00:00","dateModified":"2021-10-12T15:20:11+00:00","author":{"@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7"},"description":"\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.","breadcrumb":{"@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/#primaryimage","url":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/KW40-Image-e1633564933371.jpg","contentUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/KW40-Image-e1633564933371.jpg","width":850,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/wmp.mx\/es\/mexico-se-convierte-en-miembro-del-world-logistics-passport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wmp.mx\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico se convierte en miembro del \u201cWorld Logistics Passport\u201d y llega a mercados nuevos"}]},{"@type":"WebSite","@id":"https:\/\/wmp.mx\/#website","url":"https:\/\/wmp.mx\/","name":"WMP Mexico Advisors","description":"Queretaro | Mexiko Stadt | Puebla | Stuttgart | Greenville","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wmp.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7","name":"Liv Winterfeldt","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","caption":"Liv Winterfeldt"}}]}},"_links":{"self":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/8922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/comments?post=8922"}],"version-history":[{"count":0,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/8922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/media\/8926"}],"wp:attachment":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/media?parent=8922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/categories?post=8922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/tags?post=8922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}