{"id":9276,"date":"2022-03-09T20:09:50","date_gmt":"2022-03-09T19:09:50","guid":{"rendered":"https:\/\/wmp.mx\/?p=9276"},"modified":"2022-03-09T20:09:50","modified_gmt":"2022-03-09T19:09:50","slug":"dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas","status":"publish","type":"post","link":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/","title":{"rendered":"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas"},"content":{"rendered":"<p>Cada a\u00f1o, el D\u00eda Internacional de la Mujer es una oportunidad para reflexionar sobre aspectos relacionados con el papel, la posici\u00f3n y la importancia de las mujeres, ya sea en la sociedad, la econom\u00eda, la pol\u00edtica, pero sobre todo en el mundo del trabajo.<\/p>\n<p>M\u00e9xico es un pa\u00eds donde la desigualdad de g\u00e9nero es muy evidente en el mercado laboral.  Las mujeres representan m\u00e1s del 50% de la poblaci\u00f3n. Sin embargo, s\u00f3lo el 45% de las mujeres en edad de trabajar tienen un empleo fijo. Para los hombres, en cambio, esta proporci\u00f3n es del 78%. La tasa media de participaci\u00f3n de la mujer en el mercado laboral es, por tanto, inferior a la media latinoamericana, que es del 50%. Si las tasas de participaci\u00f3n de la poblaci\u00f3n activa de mujeres y hombres fueran iguales, el PIB de M\u00e9xico podr\u00eda crecer te\u00f3ricamente un 70% en 2025.<\/p>\n<p>Y aunque la diferencia salarial entre hombres y mujeres se ha reducido en los \u00faltimos cinco a\u00f1os, seguir\u00e1 siendo de casi el 20% en 2022, seg\u00fan el Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social. Esto se debe en parte a que las mujeres dedican hasta 2,6 veces m\u00e1s tiempo al trabajo no remunerado que los hombres.<\/p>\n<p>Ahora que la econom\u00eda se recupera lentamente de la pandemia, las empresas se preparan para integrar a las mujeres m\u00e1s en el mundo laboral y facilitarles el acceso a puestos m\u00e1s altos. El 59% de las empresas del pa\u00eds tiene previsto trabajar para alcanzar este objetivo este a\u00f1o, mientras que el 29% de las organizaciones lo har\u00e1 dentro de dos a\u00f1os. Adem\u00e1s, el 74% de las empresas mexicanas persigue el objetivo de implementar la diversidad y lograr la igualdad salarial. Es necesario, especialmente en M\u00e9xico, donde las mujeres se enfrentan a cargas adicionales en la sociedad, crear un entorno que apoye el acceso a puestos clave.<\/p>\n<p>Actualmente, hay m\u00e1s mujeres que terminan sus estudios de posgrado que los hombres, una evoluci\u00f3n que deber\u00eda reflejarse especialmente en los puestos de liderazgo. Las mujeres son m\u00e1s fiables en cuanto a los pagos y las decisiones de los pr\u00e9stamos. Una de las razones es que est\u00e1n dispuestas a pedir consejo y a escuchar con atenci\u00f3n cuando se trata de pr\u00e9stamos, por lo que los cr\u00e9ditos que se les conceden suelen tener un mejor historial de pagos que los concedidos a los hombres. Romper y cambiar paradigmas no es f\u00e1cil, y las empresas se han dado cuenta de ello. Por ello, los programas de fomento de la igualdad de g\u00e9nero y de la presencia de m\u00e1s mujeres en puestos de liderazgo son importantes para muchas empresas. Un aspecto importante que contribuye a la igualdad de g\u00e9nero es la digitalizaci\u00f3n y el uso de tecnolog\u00edas desarrolladas durante la pandemia de Covid-19. Las redes sociales y otros medios de comunicaci\u00f3n tambi\u00e9n han nivelado el camino para el reconocimiento de las mujeres en el trabajo y les han dado m\u00e1s visibilidad.<\/p>\n<blockquote><p>\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o, el D\u00eda Internacional de la Mujer es una oportunidad para reflexionar sobre aspectos relacionados con el papel, la posici\u00f3n y la importancia de las mujeres, ya sea en la sociedad, la econom\u00eda, la pol\u00edtica, pero sobre todo en el mundo del trabajo. M\u00e9xico es un pa\u00eds donde la desigualdad de g\u00e9nero es muy [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":9282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-9276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas - WMP Mexico Advisors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas - WMP Mexico Advisors\" \/>\n<meta property=\"og:description\" content=\"Cada a\u00f1o, el D\u00eda Internacional de la Mujer es una oportunidad para reflexionar sobre aspectos relacionados con el papel, la posici\u00f3n y la importancia de las mujeres, ya sea en la sociedad, la econom\u00eda, la pol\u00edtica, pero sobre todo en el mundo del trabajo. M\u00e9xico es un pa\u00eds donde la desigualdad de g\u00e9nero es muy [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/\" \/>\n<meta property=\"og:site_name\" content=\"WMP Mexico Advisors\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-09T19:09:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/MicrosoftTeams-image-3-1030x687.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Liv Winterfeldt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liv Winterfeldt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/\"},\"author\":{\"name\":\"Liv Winterfeldt\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\"},\"headline\":\"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas\",\"datePublished\":\"2022-03-09T19:09:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/\"},\"wordCount\":559,\"image\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-3-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/\",\"url\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/\",\"name\":\"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas - WMP Mexico Advisors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-3-scaled.jpg\",\"datePublished\":\"2022-03-09T19:09:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-3-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/MicrosoftTeams-image-3-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Happy female professional in glasses and suit holding tablet and making winner gesture while two businessmen working behind glass wall. Copy space. Communication concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wmp.mx\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#website\",\"url\":\"https:\\\/\\\/wmp.mx\\\/\",\"name\":\"WMP Mexico Advisors\",\"description\":\"Queretaro | Mexiko Stadt | Puebla | Stuttgart | Greenville\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wmp.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\",\"name\":\"Liv Winterfeldt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"caption\":\"Liv Winterfeldt\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas - WMP Mexico Advisors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas - WMP Mexico Advisors","og_description":"Cada a\u00f1o, el D\u00eda Internacional de la Mujer es una oportunidad para reflexionar sobre aspectos relacionados con el papel, la posici\u00f3n y la importancia de las mujeres, ya sea en la sociedad, la econom\u00eda, la pol\u00edtica, pero sobre todo en el mundo del trabajo. M\u00e9xico es un pa\u00eds donde la desigualdad de g\u00e9nero es muy [&hellip;]","og_url":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/","og_site_name":"WMP Mexico Advisors","article_published_time":"2022-03-09T19:09:50+00:00","og_image":[{"width":1030,"height":687,"url":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/MicrosoftTeams-image-3-1030x687.jpg","type":"image\/jpeg"}],"author":"Liv Winterfeldt","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Liv Winterfeldt","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/#article","isPartOf":{"@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/"},"author":{"name":"Liv Winterfeldt","@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7"},"headline":"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas","datePublished":"2022-03-09T19:09:50+00:00","mainEntityOfPage":{"@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/"},"wordCount":559,"image":{"@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/#primaryimage"},"thumbnailUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/MicrosoftTeams-image-3-scaled.jpg","articleSection":["News"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/","url":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/","name":"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas - WMP Mexico Advisors","isPartOf":{"@id":"https:\/\/wmp.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/#primaryimage"},"image":{"@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/#primaryimage"},"thumbnailUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/MicrosoftTeams-image-3-scaled.jpg","datePublished":"2022-03-09T19:09:50+00:00","author":{"@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7"},"breadcrumb":{"@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/#primaryimage","url":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/MicrosoftTeams-image-3-scaled.jpg","contentUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/MicrosoftTeams-image-3-scaled.jpg","width":2560,"height":1706,"caption":"Happy female professional in glasses and suit holding tablet and making winner gesture while two businessmen working behind glass wall. Copy space. Communication concept"},{"@type":"BreadcrumbList","@id":"https:\/\/wmp.mx\/es\/dia-internacional-de-la-mujer-el-poder-de-las-mujeres-mexicanas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wmp.mx\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Internacional de la Mujer: El poder de las mujeres mexicanas"}]},{"@type":"WebSite","@id":"https:\/\/wmp.mx\/#website","url":"https:\/\/wmp.mx\/","name":"WMP Mexico Advisors","description":"Queretaro | Mexiko Stadt | Puebla | Stuttgart | Greenville","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wmp.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7","name":"Liv Winterfeldt","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","caption":"Liv Winterfeldt"}}]}},"_links":{"self":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/9276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/comments?post=9276"}],"version-history":[{"count":2,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/9276\/revisions"}],"predecessor-version":[{"id":9289,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/9276\/revisions\/9289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/media\/9282"}],"wp:attachment":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/media?parent=9276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/categories?post=9276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/tags?post=9276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}