{"id":9678,"date":"2022-06-03T23:26:33","date_gmt":"2022-06-03T21:26:33","guid":{"rendered":"https:\/\/wmp.mx\/manual-de-cultura-hacer-negocios-en-mexico\/"},"modified":"2022-06-03T23:35:52","modified_gmt":"2022-06-03T21:35:52","slug":"manual-de-cultura-hacer-negocios-en-mexico","status":"publish","type":"post","link":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/","title":{"rendered":"Manual de cultura: Hacer negocios en M\u00e9xico"},"content":{"rendered":"<h3>Gesti\u00f3n y comprensi\u00f3n de la cultura empresarial mexicana<\/h3>\n<p>Para hacer negocios con \u00e9xito en M\u00e9xico, no s\u00f3lo hay que conocer las normas y las leyes del pa\u00eds, sino tambi\u00e9n sus modales y su cultura empresarial. Por lo general, en M\u00e9xico se espera que un directivo muestre integridad, confianza y sinceridad hacia el personal. Los mexicanos est\u00e1n acostumbrados y toleran una forma de liderazgo m\u00e1s autocr\u00e1tica y vertical, de la que se acostumbra practicar en Alemania. Por lo tanto, la gesti\u00f3n intercultural debe familiarizarse con la forma jer\u00e1rquica en la que se dirigen las empresas en M\u00e9xico y c\u00f3mo se toman las decisiones.<\/p>\n<p>Es especialmente importante entender que la familia y los amigos son tradicionalmente lo primero para un trabajador mexicano. Por lo tanto, las obligaciones familiares pueden, en algunos casos, tener prioridad sobre el desempe\u00f1o profesional. Al iniciar a hacer negocios en M\u00e9xico, es especialmente importante tener en cuenta que la construcci\u00f3n de una amistad con gente involucrada\u00a0 debe ser una prioridad para garantizar el \u00e9xito de las operaciones. Mientras que los trabajadores de otros pa\u00edses suelen tratar de trazar una l\u00ednea entre las relaciones interpersonales y las empresariales, la l\u00ednea entre ambas no est\u00e1 tan claramente definida en el lugar de trabajo mexicano. Especialmente en las empresas medianas, los mexicanos est\u00e1n m\u00e1s interesados en establecer relaciones personales a largo plazo con sus compa\u00f1eros y directivos que en el estatus de la empresa a la que representan.<\/p>\n<h3>Negociaciones<\/h3>\n<p>En el contexto de las negociaciones, hay que tener en cuenta algunas cosas. Las empresas est\u00e1n estructuradas seg\u00fan una estricta jerarqu\u00eda. La apariencia externa y los s\u00edmbolos de estatus son especialmente importantes. Por regla general, las negociaciones comienzan con una peque\u00f1a charla para conocerse y establecer una relaci\u00f3n de confianza. Los temas aceptados son la familia, el clima, los destinos de viaje en M\u00e9xico y las especialidades culinarias. Deben evitarse los temas que impliquen cr\u00edticas, como la corrupci\u00f3n y la delincuencia.<\/p>\n<p>Es habitual cenar con un socio comercial, pero los temas de negocios s\u00f3lo se tratan despu\u00e9s de la comida. Cuando se trata de acuerdos y convenios, los mexicanos son maestros de las declaraciones indirectas. Es habitual no responder con un &#8220;s\u00ed&#8221; o un &#8220;no&#8221; inequ\u00edvoco. Por lo tanto, un &#8220;s\u00ed&#8221; debe tomarse como un &#8220;probablemente&#8221;.<\/p>\n<h3>Tiempo y reglas<\/h3>\n<p>Cuando se trata de tiempo o reglas, los mexicanos son bastante flexibles. Es importante vivir el momento y los planes a largo plazo juegan un papel secundario. Adem\u00e1s, la cultura mexicana es conocida por su comprensi\u00f3n policr\u00f3nica del tiempo, lo que significa que se hacen varias cosas al mismo tiempo. Llegar tarde es normal, e incluso en un entorno profesional, se acepta y tolera hasta una hora. Cumplir con las citas o los plazos tampoco tiene la misma importancia que en la cultura alemana y la improvisaci\u00f3n y el manejo flexible son la norma aqu\u00ed.<\/p>\n<blockquote><p>\u00bfTiene m\u00e1s dudas sobre la evoluci\u00f3n econ\u00f3mica actual de M\u00e9xico? No dude en ponerse en contacto con nosotros.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Gesti\u00f3n y comprensi\u00f3n de la cultura empresarial mexicana Para hacer negocios con \u00e9xito en M\u00e9xico, no s\u00f3lo hay que conocer las normas y las leyes del pa\u00eds, sino tambi\u00e9n sus modales y su cultura empresarial. Por lo general, en M\u00e9xico se espera que un directivo muestre integridad, confianza y sinceridad hacia el personal. Los mexicanos [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":9669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"mc4wp_mailchimp_campaign":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-9678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manual de cultura: Hacer negocios en M\u00e9xico - WMP Mexico Advisors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manual de cultura: Hacer negocios en M\u00e9xico - WMP Mexico Advisors\" \/>\n<meta property=\"og:description\" content=\"Gesti\u00f3n y comprensi\u00f3n de la cultura empresarial mexicana Para hacer negocios con \u00e9xito en M\u00e9xico, no s\u00f3lo hay que conocer las normas y las leyes del pa\u00eds, sino tambi\u00e9n sus modales y su cultura empresarial. Por lo general, en M\u00e9xico se espera que un directivo muestre integridad, confianza y sinceridad hacia el personal. Los mexicanos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"WMP Mexico Advisors\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-03T21:26:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-03T21:35:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/Design-ohne-Titel-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Liv Winterfeldt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Liv Winterfeldt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/\"},\"author\":{\"name\":\"Liv Winterfeldt\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\"},\"headline\":\"Manual de cultura: Hacer negocios en M\u00e9xico\",\"datePublished\":\"2022-06-03T21:26:33+00:00\",\"dateModified\":\"2022-06-03T21:35:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/\"},\"wordCount\":541,\"image\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/Design-ohne-Titel-1-1.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/\",\"url\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/\",\"name\":\"Manual de cultura: Hacer negocios en M\u00e9xico - WMP Mexico Advisors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/Design-ohne-Titel-1-1.png\",\"datePublished\":\"2022-06-03T21:26:33+00:00\",\"dateModified\":\"2022-06-03T21:35:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/Design-ohne-Titel-1-1.png\",\"contentUrl\":\"https:\\\/\\\/wmp.mx\\\/UP1\\\/wp-content\\\/uploads\\\/Design-ohne-Titel-1-1.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/es\\\/manual-de-cultura-hacer-negocios-en-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wmp.mx\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manual de cultura: Hacer negocios en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#website\",\"url\":\"https:\\\/\\\/wmp.mx\\\/\",\"name\":\"WMP Mexico Advisors\",\"description\":\"Queretaro | Mexiko Stadt | Puebla | Stuttgart | Greenville\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wmp.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wmp.mx\\\/#\\\/schema\\\/person\\\/3c9538a21ca298c9e6eaab89731cf8f7\",\"name\":\"Liv Winterfeldt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g\",\"caption\":\"Liv Winterfeldt\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manual de cultura: Hacer negocios en M\u00e9xico - WMP Mexico Advisors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Manual de cultura: Hacer negocios en M\u00e9xico - WMP Mexico Advisors","og_description":"Gesti\u00f3n y comprensi\u00f3n de la cultura empresarial mexicana Para hacer negocios con \u00e9xito en M\u00e9xico, no s\u00f3lo hay que conocer las normas y las leyes del pa\u00eds, sino tambi\u00e9n sus modales y su cultura empresarial. Por lo general, en M\u00e9xico se espera que un directivo muestre integridad, confianza y sinceridad hacia el personal. Los mexicanos [&hellip;]","og_url":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/","og_site_name":"WMP Mexico Advisors","article_published_time":"2022-06-03T21:26:33+00:00","article_modified_time":"2022-06-03T21:35:52+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/Design-ohne-Titel-1-1.png","type":"image\/png"}],"author":"Liv Winterfeldt","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Liv Winterfeldt","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/#article","isPartOf":{"@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/"},"author":{"name":"Liv Winterfeldt","@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7"},"headline":"Manual de cultura: Hacer negocios en M\u00e9xico","datePublished":"2022-06-03T21:26:33+00:00","dateModified":"2022-06-03T21:35:52+00:00","mainEntityOfPage":{"@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/"},"wordCount":541,"image":{"@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/Design-ohne-Titel-1-1.png","articleSection":["News"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/","url":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/","name":"Manual de cultura: Hacer negocios en M\u00e9xico - WMP Mexico Advisors","isPartOf":{"@id":"https:\/\/wmp.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/#primaryimage"},"image":{"@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/Design-ohne-Titel-1-1.png","datePublished":"2022-06-03T21:26:33+00:00","dateModified":"2022-06-03T21:35:52+00:00","author":{"@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7"},"breadcrumb":{"@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/#primaryimage","url":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/Design-ohne-Titel-1-1.png","contentUrl":"https:\/\/wmp.mx\/UP1\/wp-content\/uploads\/Design-ohne-Titel-1-1.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/wmp.mx\/es\/manual-de-cultura-hacer-negocios-en-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wmp.mx\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Manual de cultura: Hacer negocios en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/wmp.mx\/#website","url":"https:\/\/wmp.mx\/","name":"WMP Mexico Advisors","description":"Queretaro | Mexiko Stadt | Puebla | Stuttgart | Greenville","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wmp.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/wmp.mx\/#\/schema\/person\/3c9538a21ca298c9e6eaab89731cf8f7","name":"Liv Winterfeldt","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d26b249f471b3d44d31916bb084e76206caac1239130bb66efe719c7cddd441?s=96&d=mm&r=g","caption":"Liv Winterfeldt"}}]}},"_links":{"self":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/9678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/comments?post=9678"}],"version-history":[{"count":1,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/9678\/revisions"}],"predecessor-version":[{"id":9681,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/posts\/9678\/revisions\/9681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/media\/9669"}],"wp:attachment":[{"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/media?parent=9678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/categories?post=9678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wmp.mx\/es\/wp-json\/wp\/v2\/tags?post=9678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}